{"id":11778,"date":"2023-03-23T17:22:24","date_gmt":"2023-03-23T20:22:24","guid":{"rendered":"https:\/\/centrosabia.org.br\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/"},"modified":"2023-03-23T17:32:15","modified_gmt":"2023-03-23T20:32:15","slug":"governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife","status":"publish","type":"post","link":"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/","title":{"rendered":"El Gobierno Lula lanza pol\u00edticas y proyectos en un gran acto en Recife"},"content":{"rendered":"\n<div class=\"wp-block-stackable-subtitle stk-block-subtitle stk-block stk-0566ac8\" data-block-id=\"0566ac8\"><p class=\"stk-block-subtitle__text stk-subtitle\"><em><span style=\"color: var(--theme-palette-color-2, #adac22);\" class=\"stk-highlight\">Agricultores del campo y la ciudad llenaron el Geraldao para celebrar la reanudaci\u00f3n de las pol\u00edticas de agricultura familiar y agroecolog\u00eda<\/span><\/em><\/p><\/div>\n\n<p class=\"wp-block-paragraph\"><strong>Rosa Sampaio, periodista del Centro Sabi\u00e1<\/strong><\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/17_Menino-Angelo-Comida-de-Verdade_Rio-Formoso_PE_2020-1024x683.jpg\" alt=\"\" class=\"wp-image-11763\" srcset=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/17_Menino-Angelo-Comida-de-Verdade_Rio-Formoso_PE_2020-1024x683.jpg 1024w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/17_Menino-Angelo-Comida-de-Verdade_Rio-Formoso_PE_2020-300x200.jpg 300w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/17_Menino-Angelo-Comida-de-Verdade_Rio-Formoso_PE_2020-768x512.jpg 768w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/17_Menino-Angelo-Comida-de-Verdade_Rio-Formoso_PE_2020-1536x1024.jpg 1536w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/17_Menino-Angelo-Comida-de-Verdade_Rio-Formoso_PE_2020-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Nay Jinknss \/ Colecci\u00f3n Sabi\u00e1 Center<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Mi\u00e9rcoles (22) de celebraciones para los agricultores de Pernambuco, con la visita del presidente Lula y su comitiva para relanzar el Programa de Adquisici\u00f3n de Alimentos (PAA), a trav\u00e9s de una Medida Provisional, en el abarrotado Gimnasio Geraldao de Recife. Mujeres y hombres del campo y la ciudad acompa\u00f1aron los anuncios y la firma de los decretos de la reanudaci\u00f3n de la actividad agropecuaria y de las nuevas pol\u00edticas p\u00fablicas para la agricultura familiar y la Agroecolog\u00eda.<\/p>\n\n<p class=\"wp-block-paragraph\">Agricultores del campo y de la ciudad, representantes de organizaciones y movimientos sociales, como las organizaciones que integran la Articulaci\u00f3n del Semi\u00e1rido (ASA) en Pernambuco, as\u00ed como miembros de la Coordinaci\u00f3n Ejecutiva de ASA, de la Red ATER y de la Articulaci\u00f3n Nacional de Agroecolog\u00eda (ANA) en el estado, escucharon el compromiso del presidente de combatir el hambre y dignificar a las personas que producen alimentos para los brasile\u00f1os, a trav\u00e9s de la comercializaci\u00f3n justa de alimentos sanos y libres de veneno.<\/p>\n\n<p class=\"wp-block-paragraph\">El nuevo PAA incluye un aumento de la cantidad individual que pueden vender los agricultores familiares, un acceso m\u00e1s f\u00e1cil para los pueblos ind\u00edgenas y las comunidades tradicionales, y una mayor participaci\u00f3n de las mujeres en la aplicaci\u00f3n del programa. El tope ser\u00e1 aumentado de R$ 12.000 para R$ 15.000 en las modalidades de Donaci\u00f3n Simult\u00e1nea, Formaci\u00f3n de Existencias y Compra Directa.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-23-at-17.20.43-1024x682.jpeg\" alt=\"\" class=\"wp-image-11772\" srcset=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-23-at-17.20.43-1024x682.jpeg 1024w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-23-at-17.20.43-300x200.jpeg 300w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-23-at-17.20.43-768x512.jpeg 768w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-23-at-17.20.43-1536x1023.jpeg 1536w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-23-at-17.20.43.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Ripper \/ Colecci\u00f3n del Centro Sabi\u00e1<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Otro objetivo del Programa es aumentar el porcentaje de mujeres agricultoras del 46% a por lo menos el 50%, a trav\u00e9s del Programa de Organizaci\u00f3n Econ\u00f3mica Productiva de la Mujer Rural, como anunci\u00f3 el ministro Paulo Teixeira, de la cartera de Desarrollo Agrario y Agricultura Familiar, \u00ablas mujeres tendr\u00e1n su propio programa para comercializar sus productos, garantizando la compra de alimentos producidos en sus traspatios productivos\u00bb.<\/p>\n\n<p class=\"wp-block-paragraph\">El ministro Paulo Teixeira tambi\u00e9n destac\u00f3 la importancia de que los municipios y los estados compren el 30% del total de los recursos destinados a la alimentaci\u00f3n escolar directamente a las explotaciones familiares a trav\u00e9s del Programa Nacional de Alimentaci\u00f3n Escolar (PNAE). En esta ocasi\u00f3n, tambi\u00e9n se firm\u00f3 el decreto por el que se restablece el Consejo Nacional de Desarrollo Rural Sostenible &#8211; CONDRAF.<\/p>\n\n<p class=\"wp-block-paragraph\">Semi\u00e1rido &#8211; Durante el anuncio de la reanudaci\u00f3n del PAA, la Directora Socioambiental del BNDES, Tereza Campello, lanz\u00f3 el proyecto \u00abSembrando Resiliencia Clim\u00e1tica en Comunidades Rurales del Nordeste\u00bb, junto con el Fondo Internacional de Desarrollo Agr\u00edcola (FIDA), destinado a la poblaci\u00f3n rural de la regi\u00f3n semi\u00e1rida brasile\u00f1a.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-23-at-17.17.39-1024x682.jpeg\" alt=\"\" class=\"wp-image-11766\" srcset=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-23-at-17.17.39-1024x682.jpeg 1024w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-23-at-17.17.39-300x200.jpeg 300w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-23-at-17.17.39-768x512.jpeg 768w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-23-at-17.17.39-1536x1023.jpeg 1536w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-23-at-17.17.39.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Ana Mendes \/ Colecci\u00f3n Sabi\u00e1 Center<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el director, el proyecto pretende impactar a cerca de un mill\u00f3n de personas, de las cuales el 40% ser\u00e1n mujeres y el 50% j\u00f3venes, alcanzando una superficie de unas 84 mil hect\u00e1reas y restaurando ecosistemas degradados. Se implantar\u00e1n 21.000 cisternas y 16.000 unidades de tratamiento y reutilizaci\u00f3n de aguas residuales dom\u00e9sticas. \u00abEste proyecto se inspira en las experiencias brasile\u00f1as de lucha contra la pobreza y el hambre de 2003 a 2015 y en los programas de Articula\u00e7\u00e3o Semi\u00e1rido, ASA, nuestro socio. Hemos reunido estos conocimientos para garantizar la seguridad y la soberan\u00eda alimentarias de las comunidades rurales de la regi\u00f3n semi\u00e1rida del Nordeste, preparar a estas comunidades para hacer frente al cambio clim\u00e1tico en la Caatinga y reducir las emisiones de carbono\u00bb, explic\u00f3 Tereza Campello.<\/p>\n\n<p class=\"wp-block-paragraph\">El proyecto, que a\u00fan ir\u00e1 al Senado, cuenta con 129,5 millones de d\u00f3lares, unos 1.000 millones de reales, al cambio actual, recaudados con el FIDA. \u00abUna vez aprobado, ser\u00e1 implementado en los estados. Ser\u00e1n mil millones de reales para 250 mil agricultores familiares, con patios productivos y 21 mil cisternas, en el D\u00eda Mundial del Agua (22 de marzo)\u00bb, anunci\u00f3 el director del BNDES.<\/p>\n\n<p class=\"wp-block-paragraph\">A\u00fan as\u00ed, seg\u00fan Tereza Campello, la expectativa es que el proyecto se convierta en una referencia de agricultura sostenible para varios trabajadores rurales del mundo que, al igual que en la Caatinga, tambi\u00e9n sufren con los efectos adversos del cambio clim\u00e1tico. Tambi\u00e9n prev\u00e9 rutas de intercambio nacionales e internacionales (Am\u00e9rica Latina y \u00c1frica) entre agricultores y agricultoras de biomas similares.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":11750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ano":0,"footnotes":""},"categories":[218],"tags":[],"class_list":["post-11778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-es"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Gobierno Lula lanza pol\u00edticas y proyectos en un gran acto en Recife - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno Lula lanza pol\u00edticas y proyectos en un gran acto en Recife - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-23T20:22:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-23T20:32:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/ACS_2103022836-2-300x200.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Darliton\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Darliton\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/03\\\/23\\\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/03\\\/23\\\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\\\/\"},\"author\":{\"name\":\"Darliton\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/person\\\/7e83deaeb43644ce5b93a21b9d24c8d6\"},\"headline\":\"El Gobierno Lula lanza pol\u00edticas y proyectos en un gran acto en Recife\",\"datePublished\":\"2023-03-23T20:22:24+00:00\",\"dateModified\":\"2023-03-23T20:32:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/03\\\/23\\\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\\\/\"},\"wordCount\":762,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/03\\\/23\\\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ACS_2103022836-2-scaled.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/03\\\/23\\\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/03\\\/23\\\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\\\/\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/03\\\/23\\\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\\\/\",\"name\":\"El Gobierno Lula lanza pol\u00edticas y proyectos en un gran acto en Recife - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/03\\\/23\\\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/03\\\/23\\\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ACS_2103022836-2-scaled.jpg\",\"datePublished\":\"2023-03-23T20:22:24+00:00\",\"dateModified\":\"2023-03-23T20:32:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/03\\\/23\\\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/03\\\/23\\\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/03\\\/23\\\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ACS_2103022836-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ACS_2103022836-2-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"A Comunidade de Santa Rita tem o hist\u00f3rico comum com a Comunidade Quilombola de \u00c1guas Claras \u2013 ela foi fundada por uma fam\u00edlia que saiu de \u00c1guas Claras. \u00c1guas Claras por sua vez, come\u00e7ou a ser povoada em 1850 quando chegaram os primeiros moradores (Jo\u00e3o Patr\u00edcio, Z\u00e9 Gago, Petunila, Brasiliana, Maria da On\u00e7a e Const\u00e2ncia). A comunidade fica em uma regi\u00e3o serrana de dif\u00edcil acesso. \u00c9 um local cercado por serras e pr\u00f3ximo do ponto mais alto de Pernambuco \u2013 o Pico do Papagaio, que tem aproximadamente 1.200m de altitude. Vindos do Quilombo do Livramento em busca de terra para morar e produzir, aos poucos as fam\u00edlias foram formando a comunidade. Suas moradias eram feitas de taipas e pedras pelos pr\u00f3prios artes\u00e3os do Quilombo. A comunidade apresenta este nome devido \u00e0 grande quantidade de \u00e1gua doce e cristalina que nela se encontra. As pessoas desta comunidade n\u00e3o tinham terra pr\u00f3pria para produzir e trabalhavam em lavouras de fazendeiros. No ano de 2004 a comunidade come\u00e7ou a receber assessoria t\u00e9cnica do Centro Sabi\u00e1 atrav\u00e9s do projeto Dom Helder C\u00e2mara. Em 2006 passaram a receber apoio do Grupo Mulher Maravilha, que trabalha com comunidades Quilombolas. A partir de 2008 desenvolveram um projeto Tankal\u00e9, que \u00e9 uma forma\u00e7\u00e3o para o auto registro audiovisual.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/03\\\/23\\\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno Lula lanza pol\u00edticas y proyectos en un gran acto en Recife\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\",\"name\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\",\"name\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo.png\",\"width\":174,\"height\":84,\"caption\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/person\\\/7e83deaeb43644ce5b93a21b9d24c8d6\",\"name\":\"Darliton\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/abb43c9d012bc9e4677cba1d82588694a509da0a3479cb06ce66c26da27e1642?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/abb43c9d012bc9e4677cba1d82588694a509da0a3479cb06ce66c26da27e1642?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/abb43c9d012bc9e4677cba1d82588694a509da0a3479cb06ce66c26da27e1642?s=96&d=mm&r=g\",\"caption\":\"Darliton\"},\"description\":\"Comunicador popular, administrador, p\u00f3s-graduado em projetos sociais e pol\u00edticas p\u00fablicas, especialista media social, militante da agroecologia, conviv\u00eancia com semi\u00e1rido, direitos humanos, preserva\u00e7\u00e3o ambiental e direitos de trabalhadoras e trabalhadores.\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/author\\\/darliton\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno Lula lanza pol\u00edticas y proyectos en un gran acto en Recife - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno Lula lanza pol\u00edticas y proyectos en un gran acto en Recife - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","og_url":"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/","og_site_name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","article_published_time":"2023-03-23T20:22:24+00:00","article_modified_time":"2023-03-23T20:32:15+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/ACS_2103022836-2-300x200.jpg","type":"image\/jpeg"}],"author":"Darliton","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Darliton","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/#article","isPartOf":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/"},"author":{"name":"Darliton","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/person\/7e83deaeb43644ce5b93a21b9d24c8d6"},"headline":"El Gobierno Lula lanza pol\u00edticas y proyectos en un gran acto en Recife","datePublished":"2023-03-23T20:22:24+00:00","dateModified":"2023-03-23T20:32:15+00:00","mainEntityOfPage":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/"},"wordCount":762,"commentCount":0,"publisher":{"@id":"https:\/\/centrosabia.org.br\/es\/#organization"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/#primaryimage"},"thumbnailUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/ACS_2103022836-2-scaled.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/","url":"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/","name":"El Gobierno Lula lanza pol\u00edticas y proyectos en un gran acto en Recife - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","isPartOf":{"@id":"https:\/\/centrosabia.org.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/#primaryimage"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/#primaryimage"},"thumbnailUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/ACS_2103022836-2-scaled.jpg","datePublished":"2023-03-23T20:22:24+00:00","dateModified":"2023-03-23T20:32:15+00:00","breadcrumb":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/#primaryimage","url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/ACS_2103022836-2-scaled.jpg","contentUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/03\/ACS_2103022836-2-scaled.jpg","width":2560,"height":1707,"caption":"A Comunidade de Santa Rita tem o hist\u00f3rico comum com a Comunidade Quilombola de \u00c1guas Claras \u2013 ela foi fundada por uma fam\u00edlia que saiu de \u00c1guas Claras. \u00c1guas Claras por sua vez, come\u00e7ou a ser povoada em 1850 quando chegaram os primeiros moradores (Jo\u00e3o Patr\u00edcio, Z\u00e9 Gago, Petunila, Brasiliana, Maria da On\u00e7a e Const\u00e2ncia). A comunidade fica em uma regi\u00e3o serrana de dif\u00edcil acesso. \u00c9 um local cercado por serras e pr\u00f3ximo do ponto mais alto de Pernambuco \u2013 o Pico do Papagaio, que tem aproximadamente 1.200m de altitude. Vindos do Quilombo do Livramento em busca de terra para morar e produzir, aos poucos as fam\u00edlias foram formando a comunidade. Suas moradias eram feitas de taipas e pedras pelos pr\u00f3prios artes\u00e3os do Quilombo. A comunidade apresenta este nome devido \u00e0 grande quantidade de \u00e1gua doce e cristalina que nela se encontra. As pessoas desta comunidade n\u00e3o tinham terra pr\u00f3pria para produzir e trabalhavam em lavouras de fazendeiros. No ano de 2004 a comunidade come\u00e7ou a receber assessoria t\u00e9cnica do Centro Sabi\u00e1 atrav\u00e9s do projeto Dom Helder C\u00e2mara. Em 2006 passaram a receber apoio do Grupo Mulher Maravilha, que trabalha com comunidades Quilombolas. A partir de 2008 desenvolveram um projeto Tankal\u00e9, que \u00e9 uma forma\u00e7\u00e3o para o auto registro audiovisual."},{"@type":"BreadcrumbList","@id":"https:\/\/centrosabia.org.br\/es\/2023\/03\/23\/governo-lula-lanca-politicas-e-projetos-em-grande-evento-no-recife\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/centrosabia.org.br\/es\/"},{"@type":"ListItem","position":2,"name":"El Gobierno Lula lanza pol\u00edticas y proyectos en un gran acto en Recife"}]},{"@type":"WebSite","@id":"https:\/\/centrosabia.org.br\/es\/#website","url":"https:\/\/centrosabia.org.br\/es\/","name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","description":"","publisher":{"@id":"https:\/\/centrosabia.org.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrosabia.org.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrosabia.org.br\/es\/#organization","name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","url":"https:\/\/centrosabia.org.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2021\/10\/logo.png","contentUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2021\/10\/logo.png","width":174,"height":84,"caption":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/person\/7e83deaeb43644ce5b93a21b9d24c8d6","name":"Darliton","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/abb43c9d012bc9e4677cba1d82588694a509da0a3479cb06ce66c26da27e1642?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/abb43c9d012bc9e4677cba1d82588694a509da0a3479cb06ce66c26da27e1642?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/abb43c9d012bc9e4677cba1d82588694a509da0a3479cb06ce66c26da27e1642?s=96&d=mm&r=g","caption":"Darliton"},"description":"Comunicador popular, administrador, p\u00f3s-graduado em projetos sociais e pol\u00edticas p\u00fablicas, especialista media social, militante da agroecologia, conviv\u00eancia com semi\u00e1rido, direitos humanos, preserva\u00e7\u00e3o ambiental e direitos de trabalhadoras e trabalhadores.","url":"https:\/\/centrosabia.org.br\/es\/author\/darliton\/"}]}},"_links":{"self":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts\/11778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/comments?post=11778"}],"version-history":[{"count":2,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts\/11778\/revisions"}],"predecessor-version":[{"id":11782,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts\/11778\/revisions\/11782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/media\/11750"}],"wp:attachment":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/media?parent=11778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/categories?post=11778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/tags?post=11778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}