{"id":15131,"date":"2023-10-31T15:00:00","date_gmt":"2023-10-31T18:00:00","guid":{"rendered":"https:\/\/centrosabia.org.br\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/"},"modified":"2023-11-06T12:07:52","modified_gmt":"2023-11-06T15:07:52","slug":"agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes","status":"publish","type":"post","link":"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/","title":{"rendered":"Agroecolog\u00eda: una forma sostenible de alimentar al mundo y preservar nuestras ra\u00edces"},"content":{"rendered":"\n<p><strong>Islandia Bezerra,<br\/>Extensionista, investigador y profesor asociado de la Facultad de Nutrici\u00f3n de la Universidad Federal de Alagoas. Forma parte del equipo del Gobierno Federal en la Direcci\u00f3n de Di\u00e1logos de la Secretar\u00eda Nacional de Di\u00e1logos Sociales y Articulaci\u00f3n de Pol\u00edticas P\u00fablicas.<\/strong><\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/10\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-1024x683.jpg\" alt=\"\" class=\"wp-image-15042\" srcset=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/10\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-1024x683.jpg 1024w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/10\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-300x200.jpg 300w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/10\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-768x512.jpg 768w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/10\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-1536x1024.jpg 1536w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/10\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Feria Agroecol\u00f3gica de Caruaru. Foto: PH Reinaux\/Colecci\u00f3n Centro Sabi\u00e1<\/em><\/figcaption><\/figure>\n\n<p>Reflexionar, escuchar, hablar y escribir sobre el <strong>hambre <\/strong>es dif\u00edcil y supone un reto. Sobre todo cuando los alimentos, las preparaciones, los nutrientes, as\u00ed como las consistencias, los colores, los olores, los sabores y los recuerdos alimentarios representan la cultura de un pueblo y, por tanto, la centralidad del ser en la sociedad.<\/p>\n\n<p>El reto tambi\u00e9n se expresa en la definici\u00f3n del t\u00e9rmino <strong>hambre<\/strong>. En 1946, Josu\u00e9 de Castro grit\u00f3 al mundo que el hambre (no tener para comer o no disponer de medios para producir y\/o comprar alimentos) es un fen\u00f3meno econ\u00f3mico, social y, sobre todo, <strong>pol\u00edtico<\/strong>. D\u00e9cadas m\u00e1s tarde, esta definici\u00f3n del t\u00e9rmino apareci\u00f3 en la canci\u00f3n del grupo Tit\u00e3s:<em>\u00abno s\u00f3lo queremos comida, queremos comida, diversi\u00f3n y arte<\/em>\u00ab. Casi 40 a\u00f1os despu\u00e9s de estas letras y melod\u00edas que invitan a la reflexi\u00f3n, hablar de <strong>comida <\/strong>es m\u00e1s actual y necesario que en el momento de su lanzamiento.<\/p>\n\n<p>El hambre est\u00e1 presente en la vida de<strong> 33 millones de<\/strong> brasile\u00f1os, seg\u00fan la Red Brasile\u00f1a de Investigaci\u00f3n sobre Soberan\u00eda y Seguridad Alimentaria y Nutricional (Rede PENSSAN). Seg\u00fan la ONU, unos <strong>828 millones de<\/strong> personas pasar\u00e1n hambre en el mundo en 2021, y esta previsi\u00f3n va a aumentar.<\/p>\n\n<p>Pero no basta con pensar en este fen\u00f3meno como un reto, sin retarnos (la redundancia aqu\u00ed es deliberada) a pensar y actuar para resolverlo. Retomando la frase de Tit\u00e3s<em>\u00abNo queremos s\u00c3\u00b3lo comida, queremos la vida como la vida<\/em> la quiere\u00bb, me pregunto: \u00c2\u00bfc\u00c3\u00b3mo quiere la vida la vida?<\/p>\n\n<p>En un contexto de crisis clim\u00e1tica que se agrava como consecuencia de un sistema alimentario hegem\u00f3nico que trabaja para enfermar, mutilar, contaminar, expulsar, expropiar y matar a las personas y a la naturaleza, tenemos un posible camino a seguir:  <strong>agroecolog\u00eda<\/strong>La agroecolog\u00eda es un hilo lleno de conocimientos, saberes y pr\u00e1cticas que teje una enmara\u00f1ada y compleja red de  <strong>vidas<\/strong>. Pero tenemos que hacer m\u00e1s para materializar<em>\u00abla vida como la vida quiere<\/em>ser\u00bb.<\/p>\n\n<p>La vida quiere alimentos, preparaciones adecuadas y sanas, culturalmente referenciadas y, sobre todo, biodiversas, que traigan consigo, en la vida y en el plato, los colores, olores y sabores de nuestros biomas:<br\/><br\/><strong>De la Amazonia<\/strong> que trae sus ingredientes en preparaciones de pescados, verduras y tub\u00e9rculos que laten y tiemblan como la diversidad de saberes ancestrales al plato cotidiano, as\u00ed como la agroecolog\u00eda de la regi\u00f3n que impulsa y fortalece tales pr\u00e1cticas;<br\/><strong>De la Caatinga<\/strong>, que contiene sabores, olores y texturas propios del lugar, pero que, debido al actual modelo depredador, ha ido agotando estas riquezas, y la agroecolog\u00eda se presenta como el camino hacia una posible soluci\u00f3n;<br\/><strong>Del Cerrado<\/strong> <strong>y del Pantanal (bioma de transici\u00f3n)<\/strong>, biomas que atraviesan estados geogr\u00e1ficamente delimitados, pero que encuentran en los alimentos \u00abde ra\u00edz\u00bb la presencia marcada de frutos, ra\u00edces, semillas, nueces, que llenan los ojos, la boca y la barriga (como decimos aqu\u00ed en nuestra regi\u00f3n nordeste). La agroecolog\u00eda en estos biomas ha rescatado pr\u00e1cticas de producir-comer que subvierten la l\u00f3gica de los monocultivos circundantes.<br\/><strong>Del Bosque<\/strong> Atl\u00e1ntico &#8211; este bioma diverso y amenazado representa una necesidad real y urgente de reforzar la agroecolog\u00eda, simplemente porque es VIDA. Sin duda, si se preserva, desempe\u00f1ar\u00e1 un papel decisivo en la lucha contra el hambre.<br\/><strong>De la Pampa<\/strong> &#8211; a pesar de su menor abundancia en variedades de especies, es de este lugar que Brasil experimenta aromas y sabores que expresan culturas diversas, pero que tambi\u00e9n sufren los procesos del monocultivo. Por otro lado, la agroecolog\u00eda en este bioma viene rescatando procesos de reconexi\u00f3n entre producir y comer, transformando vidas y territorios.<br\/><br\/>Entre las riquezas de los biomas, podemos estar seguros de una cosa: acabar con el hambre significa preservar lo m\u00e1s valioso que tenemos: los biomas y las culturas. Estamos hechos de alimentos, de preparaciones que traen consigo historias, recetas, recuerdos&#8230; no se producen en las estanter\u00edas de mercados y supermercados. Se cr\u00edan, alimentan y nutren en los patios traseros, en la granja, en los espacios colectivos de producci\u00f3n y alimentaci\u00f3n, en las parcelas de los asentamientos de reforma agraria, pero tambi\u00e9n en las zonas de la periferia de los grandes centros urbanos, donde la agroecolog\u00eda produce nuevas relaciones entre la sociedad y la naturaleza, y entre la sociedad y ella misma.  <strong>La agroecolog\u00eda como posible soluci\u00f3n para acabar con el hambre en el mundo no es una utop\u00eda. Se trata de preservar tu propia existencia.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Octubre, Mes Mundial de la Alimentaci\u00f3n, nos trae la urgencia de reflexionar sobre el problema del hambre, as\u00ed como de pensar en posibles soluciones para acabar con esta lacra.<\/p>\n","protected":false},"author":6,"featured_media":15044,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ano":0,"footnotes":""},"categories":[218],"tags":[273,420,914,1995],"class_list":["post-15131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-es","tag-agroecologia-es","tag-alimentacion","tag-comida-de-verdade-es","tag-jornal-dois-dedos-de-prosa-es"],"blocksy_meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agroecolog\u00eda: una forma sostenible de alimentar al mundo y preservar nuestras ra\u00edces - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agroecolog\u00eda: una forma sostenible de alimentar al mundo y preservar nuestras ra\u00edces - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\" \/>\n<meta property=\"og:description\" content=\"Octubre, Mes Mundial de la Alimentaci\u00f3n, nos trae la urgencia de reflexionar sobre el problema del hambre, as\u00ed como de pensar en posibles soluciones para acabar con esta lacra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-31T18:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-06T15:07:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/10\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-300x200.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"B\u00e1rbara Bittencourt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"B\u00e1rbara Bittencourt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/10\\\/31\\\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/10\\\/31\\\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\\\/\"},\"author\":{\"name\":\"B\u00e1rbara Bittencourt\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/person\\\/f03db906ca655efbc7cf3ea1014afa0f\"},\"headline\":\"Agroecolog\u00eda: una forma sostenible de alimentar al mundo y preservar nuestras ra\u00edces\",\"datePublished\":\"2023-10-31T18:00:00+00:00\",\"dateModified\":\"2023-11-06T15:07:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/10\\\/31\\\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\\\/\"},\"wordCount\":862,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/10\\\/31\\\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-scaled.jpg\",\"keywords\":[\"agroecolog\u00eda\",\"Alimentaci\u00f3n\",\"Comida De Verdade\",\"Jornal Dois Dedos de Prosa\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/10\\\/31\\\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/10\\\/31\\\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\\\/\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/10\\\/31\\\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\\\/\",\"name\":\"Agroecolog\u00eda: una forma sostenible de alimentar al mundo y preservar nuestras ra\u00edces - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/10\\\/31\\\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/10\\\/31\\\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-scaled.jpg\",\"datePublished\":\"2023-10-31T18:00:00+00:00\",\"dateModified\":\"2023-11-06T15:07:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/10\\\/31\\\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/10\\\/31\\\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/10\\\/31\\\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/10\\\/31\\\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agroecolog\u00eda: una forma sostenible de alimentar al mundo y preservar nuestras ra\u00edces\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\",\"name\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\",\"name\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo.png\",\"width\":174,\"height\":84,\"caption\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/person\\\/f03db906ca655efbc7cf3ea1014afa0f\",\"name\":\"B\u00e1rbara Bittencourt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e48abdb806324dcc55c5636a12cab13ff04683923a7799b660b17b9871721ea5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e48abdb806324dcc55c5636a12cab13ff04683923a7799b660b17b9871721ea5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e48abdb806324dcc55c5636a12cab13ff04683923a7799b660b17b9871721ea5?s=96&d=mm&r=g\",\"caption\":\"B\u00e1rbara Bittencourt\"},\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/author\\\/estagio-comunicacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agroecolog\u00eda: una forma sostenible de alimentar al mundo y preservar nuestras ra\u00edces - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/","og_locale":"es_ES","og_type":"article","og_title":"Agroecolog\u00eda: una forma sostenible de alimentar al mundo y preservar nuestras ra\u00edces - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","og_description":"Octubre, Mes Mundial de la Alimentaci\u00f3n, nos trae la urgencia de reflexionar sobre el problema del hambre, as\u00ed como de pensar en posibles soluciones para acabar con esta lacra.","og_url":"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/","og_site_name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","article_published_time":"2023-10-31T18:00:00+00:00","article_modified_time":"2023-11-06T15:07:52+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/10\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-300x200.jpg","type":"image\/jpeg"}],"author":"B\u00e1rbara Bittencourt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"B\u00e1rbara Bittencourt","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/#article","isPartOf":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/"},"author":{"name":"B\u00e1rbara Bittencourt","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/person\/f03db906ca655efbc7cf3ea1014afa0f"},"headline":"Agroecolog\u00eda: una forma sostenible de alimentar al mundo y preservar nuestras ra\u00edces","datePublished":"2023-10-31T18:00:00+00:00","dateModified":"2023-11-06T15:07:52+00:00","mainEntityOfPage":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/"},"wordCount":862,"commentCount":0,"publisher":{"@id":"https:\/\/centrosabia.org.br\/es\/#organization"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/#primaryimage"},"thumbnailUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/10\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-scaled.jpg","keywords":["agroecolog\u00eda","Alimentaci\u00f3n","Comida De Verdade","Jornal Dois Dedos de Prosa"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/","url":"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/","name":"Agroecolog\u00eda: una forma sostenible de alimentar al mundo y preservar nuestras ra\u00edces - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","isPartOf":{"@id":"https:\/\/centrosabia.org.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/#primaryimage"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/#primaryimage"},"thumbnailUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/10\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-scaled.jpg","datePublished":"2023-10-31T18:00:00+00:00","dateModified":"2023-11-06T15:07:52+00:00","breadcrumb":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/#primaryimage","url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/10\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-scaled.jpg","contentUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/10\/PROSA-DE-INTERESSE.-PH-Reinaux_A-1-1-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/centrosabia.org.br\/es\/2023\/10\/31\/agroecologia-um-caminho-sustentavel-para-alimentar-o-mundo-e-preservar-nossas-raizes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/centrosabia.org.br\/es\/"},{"@type":"ListItem","position":2,"name":"Agroecolog\u00eda: una forma sostenible de alimentar al mundo y preservar nuestras ra\u00edces"}]},{"@type":"WebSite","@id":"https:\/\/centrosabia.org.br\/es\/#website","url":"https:\/\/centrosabia.org.br\/es\/","name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","description":"","publisher":{"@id":"https:\/\/centrosabia.org.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrosabia.org.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrosabia.org.br\/es\/#organization","name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","url":"https:\/\/centrosabia.org.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2021\/10\/logo.png","contentUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2021\/10\/logo.png","width":174,"height":84,"caption":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/person\/f03db906ca655efbc7cf3ea1014afa0f","name":"B\u00e1rbara Bittencourt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e48abdb806324dcc55c5636a12cab13ff04683923a7799b660b17b9871721ea5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e48abdb806324dcc55c5636a12cab13ff04683923a7799b660b17b9871721ea5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e48abdb806324dcc55c5636a12cab13ff04683923a7799b660b17b9871721ea5?s=96&d=mm&r=g","caption":"B\u00e1rbara Bittencourt"},"url":"https:\/\/centrosabia.org.br\/es\/author\/estagio-comunicacao\/"}]}},"_links":{"self":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts\/15131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/comments?post=15131"}],"version-history":[{"count":2,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts\/15131\/revisions"}],"predecessor-version":[{"id":15135,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts\/15131\/revisions\/15135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/media\/15044"}],"wp:attachment":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/media?parent=15131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/categories?post=15131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/tags?post=15131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}