{"id":15778,"date":"2023-12-06T16:24:05","date_gmt":"2023-12-06T19:24:05","guid":{"rendered":"https:\/\/centrosabia.org.br\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/"},"modified":"2023-12-06T17:15:11","modified_gmt":"2023-12-06T20:15:11","slug":"nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral","status":"publish","type":"post","link":"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/","title":{"rendered":"Elecci\u00f3n de la nueva junta directiva de Centro Sabi\u00e1 en la Asamblea General"},"content":{"rendered":"\n<p>Centro de Comunicaci\u00f3n del Centro Sabi\u00e1 <\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-10.31.41-1024x768.jpeg\" alt=\"\" class=\"wp-image-15769\" srcset=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-10.31.41-1024x768.jpeg 1024w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-10.31.41-300x225.jpeg 300w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-10.31.41-768x576.jpeg 768w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-10.31.41-1536x1152.jpeg 1536w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-10.31.41.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>En la ma\u00f1ana del mi\u00e9rcoles (06), la sede del Centro Sabi\u00e1, en Recife, acogi\u00f3 la \u00faltima Asamblea General de 2023.<\/p>\n\n<p>En esa ocasi\u00f3n, asociados y miembros del equipo del Centro Sabi\u00e1 se reunieron para discutir el balance y las acciones realizadas en 2023, adem\u00e1s de alinear las expectativas para el a\u00f1o siguiente. Diecisiete personas participaron en el acto, entre miembros y empleados de Sabi\u00e1.<\/p>\n\n<p>En la reuni\u00f3n tambi\u00e9n se eligi\u00f3 a la nueva Junta Directiva del Centro Sabi\u00e1, que tomar\u00e1 posesi\u00f3n en enero de 2024 y permanecer\u00e1 en el cargo hasta diciembre de 2026. A partir del pr\u00f3ximo a\u00f1o, Ver\u00f4nica Santana, Sonia Lucena y Tone Cristiano ocupar\u00e1n los cargos de presidenta, vicepresidenta y secretaria, respectivamente. Y en el consejo de supervisi\u00f3n estar\u00e1n Marilene Nascimento Melo; Alaide Martins dos Santos e Ivonete Lidia Vieira.<\/p>\n\n<p>Actualmente, el consejo est\u00e1 formado por Edna Maria (Presidenta); Sonia Lucena (Vicepresidenta); Joana Santos (Secretaria); Marilene Nascimento (Consejo Fiscal); Maria Ver\u00f4nica (Consejo Fiscal) y Tone Cristiano (Consejo Fiscal).<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Para la presidenta electa, Ver\u00f4nica Santana, es un gran honor formar parte del consejo del Centro Sabi\u00e1, donde la gesti\u00f3n ser\u00e1 colegiada y participativa. \u00abEs porque realmente creo en el trabajo de esta instituci\u00f3n que vamos a continuar lo que Sabi\u00e1 viene haciendo hace m\u00e1s de 30 a\u00f1os, que es construir y fortalecer redes y articulaciones, para influir en las pol\u00edticas p\u00fablicas, especialmente cuando se trata de pol\u00edticas dirigidas a la convivencia con la regi\u00f3n semi\u00e1rida y el cambio clim\u00e1tico. El protagonismo de las mujeres y de los j\u00f3venes es visible en el trabajo de Sabi\u00e1\u00bb, explic\u00f3 Ver\u00f4nica.<\/p>\n<\/blockquote>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Seg\u00fan la vicepresidenta electa, S\u00f4nia Lucena, es estupendo formar parte de la junta de Sabi\u00e1, porque la forma de trabajar es diferente, es agradable. \u00abFue en el Centro Josu\u00e9 de Castro donde conoc\u00ed la existencia del Centro Sabi\u00e1. Durante los diez a\u00f1os de Sabi\u00e1, por ejemplo, particip\u00e9 en un seminario en el que Sebasti\u00e3o Pinheiro (ingeniero agr\u00f3nomo especializado en ingenier\u00eda forestal) formaba parte del panel. Pas\u00e9 13 a\u00f1os en el CONSEA nacional y fue esta experiencia del CONSEA la que me fortaleci\u00f3 para participar en el Centro Sabi\u00e1. Estoy muy contenta de continuar en el consejo\u00bb, declar\u00f3 S\u00f4nia Lucena.<\/p>\n<\/blockquote>\n\n<p>El Centro Sabi\u00e1 quiere dar las gracias a la Junta Directiva que concluy\u00f3 su mandato este mes de diciembre y desea a la nueva, que tomar\u00e1 posesi\u00f3n en enero, una c\u00e1lida bienvenida y un trabajo bien hecho. \u00a1Sigamos sembrando m\u00e1s vida para una mejor!<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":15771,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ano":0,"footnotes":""},"categories":[218],"tags":[2246,2247,2248],"class_list":["post-15778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-es","tag-assembleia-geral-ordinaria-es","tag-diretoria-es","tag-diretoria-centro-sabia-es"],"blocksy_meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elecci\u00f3n de la nueva junta directiva de Centro Sabi\u00e1 en la Asamblea General - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elecci\u00f3n de la nueva junta directiva de Centro Sabi\u00e1 en la Asamblea General - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-06T19:24:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-06T20:15:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-10.31.41-300x225.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"B\u00e1rbara Bittencourt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"B\u00e1rbara Bittencourt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/12\\\/06\\\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/12\\\/06\\\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\\\/\"},\"author\":{\"name\":\"B\u00e1rbara Bittencourt\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/person\\\/f03db906ca655efbc7cf3ea1014afa0f\"},\"headline\":\"Elecci\u00f3n de la nueva junta directiva de Centro Sabi\u00e1 en la Asamblea General\",\"datePublished\":\"2023-12-06T19:24:05+00:00\",\"dateModified\":\"2023-12-06T20:15:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/12\\\/06\\\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\\\/\"},\"wordCount\":455,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/12\\\/06\\\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-06-at-10.31.41.jpeg\",\"keywords\":[\"Assembleia Geral Ordin\u00e1ria\",\"Diretoria\",\"Diretoria Centro Sabi\u00e1\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/12\\\/06\\\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/12\\\/06\\\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\\\/\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/12\\\/06\\\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\\\/\",\"name\":\"Elecci\u00f3n de la nueva junta directiva de Centro Sabi\u00e1 en la Asamblea General - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/12\\\/06\\\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/12\\\/06\\\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-06-at-10.31.41.jpeg\",\"datePublished\":\"2023-12-06T19:24:05+00:00\",\"dateModified\":\"2023-12-06T20:15:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/12\\\/06\\\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/12\\\/06\\\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/12\\\/06\\\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-06-at-10.31.41.jpeg\",\"contentUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-06-at-10.31.41.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2023\\\/12\\\/06\\\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elecci\u00f3n de la nueva junta directiva de Centro Sabi\u00e1 en la Asamblea General\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\",\"name\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\",\"name\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo.png\",\"width\":174,\"height\":84,\"caption\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/person\\\/f03db906ca655efbc7cf3ea1014afa0f\",\"name\":\"B\u00e1rbara Bittencourt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e48abdb806324dcc55c5636a12cab13ff04683923a7799b660b17b9871721ea5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e48abdb806324dcc55c5636a12cab13ff04683923a7799b660b17b9871721ea5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e48abdb806324dcc55c5636a12cab13ff04683923a7799b660b17b9871721ea5?s=96&d=mm&r=g\",\"caption\":\"B\u00e1rbara Bittencourt\"},\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/author\\\/estagio-comunicacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elecci\u00f3n de la nueva junta directiva de Centro Sabi\u00e1 en la Asamblea General - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/","og_locale":"es_ES","og_type":"article","og_title":"Elecci\u00f3n de la nueva junta directiva de Centro Sabi\u00e1 en la Asamblea General - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","og_url":"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/","og_site_name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","article_published_time":"2023-12-06T19:24:05+00:00","article_modified_time":"2023-12-06T20:15:11+00:00","og_image":[{"width":300,"height":225,"url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-10.31.41-300x225.jpeg","type":"image\/jpeg"}],"author":"B\u00e1rbara Bittencourt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"B\u00e1rbara Bittencourt","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/#article","isPartOf":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/"},"author":{"name":"B\u00e1rbara Bittencourt","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/person\/f03db906ca655efbc7cf3ea1014afa0f"},"headline":"Elecci\u00f3n de la nueva junta directiva de Centro Sabi\u00e1 en la Asamblea General","datePublished":"2023-12-06T19:24:05+00:00","dateModified":"2023-12-06T20:15:11+00:00","mainEntityOfPage":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/"},"wordCount":455,"commentCount":0,"publisher":{"@id":"https:\/\/centrosabia.org.br\/es\/#organization"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/#primaryimage"},"thumbnailUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-10.31.41.jpeg","keywords":["Assembleia Geral Ordin\u00e1ria","Diretoria","Diretoria Centro Sabi\u00e1"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/","url":"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/","name":"Elecci\u00f3n de la nueva junta directiva de Centro Sabi\u00e1 en la Asamblea General - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","isPartOf":{"@id":"https:\/\/centrosabia.org.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/#primaryimage"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/#primaryimage"},"thumbnailUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-10.31.41.jpeg","datePublished":"2023-12-06T19:24:05+00:00","dateModified":"2023-12-06T20:15:11+00:00","breadcrumb":{"@id":"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/#primaryimage","url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-10.31.41.jpeg","contentUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-10.31.41.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/centrosabia.org.br\/es\/2023\/12\/06\/nova-diretoria-do-centro-sabia-e-eleita-em-assembleia-geral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/centrosabia.org.br\/es\/"},{"@type":"ListItem","position":2,"name":"Elecci\u00f3n de la nueva junta directiva de Centro Sabi\u00e1 en la Asamblea General"}]},{"@type":"WebSite","@id":"https:\/\/centrosabia.org.br\/es\/#website","url":"https:\/\/centrosabia.org.br\/es\/","name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","description":"","publisher":{"@id":"https:\/\/centrosabia.org.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrosabia.org.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrosabia.org.br\/es\/#organization","name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","url":"https:\/\/centrosabia.org.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2021\/10\/logo.png","contentUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2021\/10\/logo.png","width":174,"height":84,"caption":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/person\/f03db906ca655efbc7cf3ea1014afa0f","name":"B\u00e1rbara Bittencourt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e48abdb806324dcc55c5636a12cab13ff04683923a7799b660b17b9871721ea5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e48abdb806324dcc55c5636a12cab13ff04683923a7799b660b17b9871721ea5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e48abdb806324dcc55c5636a12cab13ff04683923a7799b660b17b9871721ea5?s=96&d=mm&r=g","caption":"B\u00e1rbara Bittencourt"},"url":"https:\/\/centrosabia.org.br\/es\/author\/estagio-comunicacao\/"}]}},"_links":{"self":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts\/15778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/comments?post=15778"}],"version-history":[{"count":2,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts\/15778\/revisions"}],"predecessor-version":[{"id":15782,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts\/15778\/revisions\/15782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/media\/15771"}],"wp:attachment":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/media?parent=15778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/categories?post=15778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/tags?post=15778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}