{"id":26491,"date":"2024-11-22T08:22:47","date_gmt":"2024-11-22T11:22:47","guid":{"rendered":"https:\/\/centrosabia.org.br\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/"},"modified":"2024-11-22T11:06:16","modified_gmt":"2024-11-22T14:06:16","slug":"justicia-climatica-en-la-capital-de-la-desigualdad-real-food","status":"publish","type":"post","link":"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/","title":{"rendered":"\u00bfJusticia clim\u00e1tica en la capital de la desigualdad? | Real Food"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/linktr.ee\/joegrafia\"><strong>Jo\u00e3o Lucas Fran\u00e7a<\/strong><\/a><strong> &#8211; Locutor y comunicador del Centro Sabi\u00e1.<\/strong><\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_capa-1024x576.webp\" alt=\"\" class=\"wp-image-26473\" srcset=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_capa-1024x576.webp 1024w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_capa-300x169.webp 300w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_capa-768x432.webp 768w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_capa-1536x864.webp 1536w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_capa-2048x1152.webp 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\"><em>Comida de Verdade <\/em>vino a debatir sobre <strong>la justicia clim\u00e1tica en la capital de la desigualdad<\/strong>.<\/p>\n\n<p class=\"wp-block-paragraph\">Las cat\u00e1strofes meteorol\u00f3gicas ya no son tan infrecuentes como hace unos a\u00f1os. De hecho, son <strong>acontecimientos anuales, previsibles y anunciados.<\/strong> Pero en todas las capitales m\u00e1s afectadas por el clima extremo, como la actual <strong>Recife <\/strong>, sigue pareciendo una sorpresa cada vez que ocurre.  <\/p>\n\n<p class=\"wp-block-paragraph\">\u00bfSabes qu\u00e9 no es sorprendente? Qui\u00e9n es el m\u00e1s afectado por la <strong>emergencia clim\u00e1tica<\/strong>. Colinas, laderas, lugares altos, riberas, canales&#8230; \u00bfQui\u00e9n sufre, qui\u00e9n muere en las <strong>tragedias anunciadas<\/strong> en Recife y en tantas otras capitales de Brasil? \u00a1Hay que luchar por la <strong>justicia clim\u00e1tica<\/strong> en una de las capitales m\u00e1s desiguales del pa\u00eds!   <\/p>\n\n<p class=\"wp-block-paragraph\">Pero, \u00bfqu\u00e9 hay de <strong>la justicia clim\u00e1tica<\/strong> en la capital de la desigualdad? De eso hablamos ahora con<strong> la<\/strong> agricultora afroecol\u00f3gica<strong> Nzinga Cavalcante<\/strong>. Nzinga es madre, t\u00e9cnica en agroecolog\u00eda en <em>Serta<\/em> y estudiante de posgrado en Agroecolog\u00eda, Campesinado y Educaci\u00f3n Popular en la UFRPE. Directora financiera de la Asociaci\u00f3n de Educaci\u00f3n, Arte, Cultura y Agroecolog\u00eda S\u00edtio Agatha.  <\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_CARD-1024x1024.webp\" alt=\"\" class=\"wp-image-26476\" srcset=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_CARD-1024x1024.webp 1024w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_CARD-300x300.webp 300w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_CARD-150x150.webp 150w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_CARD-768x768.webp 768w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_CARD.webp 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Comida de Verdade <\/strong>es tu programa de <strong>los s\u00e1bados<\/strong> para hablar de alimentaci\u00f3n y agroecolog\u00eda, valorando nuestros mercados y la cultura local. <strong>Todos los s\u00e1bados a las 10<\/strong> <strong>.<\/strong> <strong>30h<\/strong> en R\u00e1dio Universit\u00e1ria <strong>99.9 FM<\/strong> y retransmitido en R\u00e1dio Universit\u00e1ria Paulo Freire <strong>820 AM<\/strong> &#8211; Formato podcast en<a href=\"https:\/\/open.spotify.com\/show\/5Yeo5PhoEelWIpuC6cYERE?si=b9cf16f6d2eb4739\"> <strong>Spotify<\/strong><\/a><strong> <\/strong>desde el <strong>Centro Sabi\u00e1! <\/strong><a href=\"https:\/\/spoti.fi\/31VtUj5\">https:\/\/spoti.fi\/31VtUj5<\/a><\/p>\n<\/blockquote>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/08\/CDV_2024-1024x1024.jpg\" alt=\"\" class=\"wp-image-24295\" srcset=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/08\/CDV_2024-1024x1024.jpg 1024w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/08\/CDV_2024-300x300.jpg 300w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/08\/CDV_2024-150x150.jpg 150w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/08\/CDV_2024-768x767.jpg 768w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/08\/CDV_2024.jpg 1081w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":26475,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ano":0,"footnotes":""},"categories":[218],"tags":[],"class_list":["post-26491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-es"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfJusticia clim\u00e1tica en la capital de la desigualdad? | Real Food - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfJusticia clim\u00e1tica en la capital de la desigualdad? | Real Food - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-22T11:22:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-22T14:06:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_capa-300x169.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"169\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Jo\u00e3o Lucas Franca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jo\u00e3o Lucas Franca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2024\\\/11\\\/22\\\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2024\\\/11\\\/22\\\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\\\/\"},\"author\":{\"name\":\"Jo\u00e3o Lucas Franca\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/person\\\/9baeb335365a2eb7c4fb3969afdc80a3\"},\"headline\":\"\u00bfJusticia clim\u00e1tica en la capital de la desigualdad? | Real Food\",\"datePublished\":\"2024-11-22T11:22:47+00:00\",\"dateModified\":\"2024-11-22T14:06:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2024\\\/11\\\/22\\\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\\\/\"},\"wordCount\":276,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2024\\\/11\\\/22\\\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/CDV_justicaclimatica_capa.webp\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2024\\\/11\\\/22\\\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2024\\\/11\\\/22\\\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\\\/\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2024\\\/11\\\/22\\\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\\\/\",\"name\":\"\u00bfJusticia clim\u00e1tica en la capital de la desigualdad? | Real Food - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2024\\\/11\\\/22\\\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2024\\\/11\\\/22\\\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/CDV_justicaclimatica_capa.webp\",\"datePublished\":\"2024-11-22T11:22:47+00:00\",\"dateModified\":\"2024-11-22T14:06:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2024\\\/11\\\/22\\\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2024\\\/11\\\/22\\\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2024\\\/11\\\/22\\\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/CDV_justicaclimatica_capa.webp\",\"contentUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/CDV_justicaclimatica_capa.webp\",\"width\":2561,\"height\":1441},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2024\\\/11\\\/22\\\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfJusticia clim\u00e1tica en la capital de la desigualdad? | Real Food\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\",\"name\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\",\"name\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo.png\",\"width\":174,\"height\":84,\"caption\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/person\\\/9baeb335365a2eb7c4fb3969afdc80a3\",\"name\":\"Jo\u00e3o Lucas Franca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9a4ada6acce9403e8d9f7c681781ab742fc465732a5eb26e375a62444c23bab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9a4ada6acce9403e8d9f7c681781ab742fc465732a5eb26e375a62444c23bab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9a4ada6acce9403e8d9f7c681781ab742fc465732a5eb26e375a62444c23bab?s=96&d=mm&r=g\",\"caption\":\"Jo\u00e3o Lucas Franca\"},\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/author\\\/joao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfJusticia clim\u00e1tica en la capital de la desigualdad? | Real Food - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfJusticia clim\u00e1tica en la capital de la desigualdad? | Real Food - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","og_url":"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/","og_site_name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","article_published_time":"2024-11-22T11:22:47+00:00","article_modified_time":"2024-11-22T14:06:16+00:00","og_image":[{"width":300,"height":169,"url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_capa-300x169.webp","type":"image\/webp"}],"author":"Jo\u00e3o Lucas Franca","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jo\u00e3o Lucas Franca","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/#article","isPartOf":{"@id":"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/"},"author":{"name":"Jo\u00e3o Lucas Franca","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/person\/9baeb335365a2eb7c4fb3969afdc80a3"},"headline":"\u00bfJusticia clim\u00e1tica en la capital de la desigualdad? | Real Food","datePublished":"2024-11-22T11:22:47+00:00","dateModified":"2024-11-22T14:06:16+00:00","mainEntityOfPage":{"@id":"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/"},"wordCount":276,"commentCount":0,"publisher":{"@id":"https:\/\/centrosabia.org.br\/es\/#organization"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/#primaryimage"},"thumbnailUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_capa.webp","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/","url":"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/","name":"\u00bfJusticia clim\u00e1tica en la capital de la desigualdad? | Real Food - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","isPartOf":{"@id":"https:\/\/centrosabia.org.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/#primaryimage"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/#primaryimage"},"thumbnailUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_capa.webp","datePublished":"2024-11-22T11:22:47+00:00","dateModified":"2024-11-22T14:06:16+00:00","breadcrumb":{"@id":"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/#primaryimage","url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_capa.webp","contentUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2024\/11\/CDV_justicaclimatica_capa.webp","width":2561,"height":1441},{"@type":"BreadcrumbList","@id":"https:\/\/centrosabia.org.br\/es\/2024\/11\/22\/justicia-climatica-en-la-capital-de-la-desigualdad-real-food\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/centrosabia.org.br\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfJusticia clim\u00e1tica en la capital de la desigualdad? | Real Food"}]},{"@type":"WebSite","@id":"https:\/\/centrosabia.org.br\/es\/#website","url":"https:\/\/centrosabia.org.br\/es\/","name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","description":"","publisher":{"@id":"https:\/\/centrosabia.org.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrosabia.org.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrosabia.org.br\/es\/#organization","name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","url":"https:\/\/centrosabia.org.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2021\/10\/logo.png","contentUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2021\/10\/logo.png","width":174,"height":84,"caption":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/person\/9baeb335365a2eb7c4fb3969afdc80a3","name":"Jo\u00e3o Lucas Franca","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a9a4ada6acce9403e8d9f7c681781ab742fc465732a5eb26e375a62444c23bab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a9a4ada6acce9403e8d9f7c681781ab742fc465732a5eb26e375a62444c23bab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a9a4ada6acce9403e8d9f7c681781ab742fc465732a5eb26e375a62444c23bab?s=96&d=mm&r=g","caption":"Jo\u00e3o Lucas Franca"},"url":"https:\/\/centrosabia.org.br\/es\/author\/joao\/"}]}},"_links":{"self":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts\/26491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/comments?post=26491"}],"version-history":[{"count":1,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts\/26491\/revisions"}],"predecessor-version":[{"id":26492,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts\/26491\/revisions\/26492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/media\/26475"}],"wp:attachment":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/media?parent=26491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/categories?post=26491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/tags?post=26491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}