{"id":27482,"date":"2025-01-28T09:28:12","date_gmt":"2025-01-28T12:28:12","guid":{"rendered":"https:\/\/centrosabia.org.br\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/"},"modified":"2025-01-28T14:01:11","modified_gmt":"2025-01-28T17:01:11","slug":"o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar","status":"publish","type":"post","link":"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/","title":{"rendered":"El reto de las nuevas administraciones municipales con la soberan\u00eda y la seguridad alimentarias"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br\/>Por S\u00f4nia Lucena Nutricionista, profesora y vicepresidenta del Centro Sabi\u00e1<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2025\/01\/4-foto-Ana-Mendes-Prosa-de-Interesse-1024x683.jpg\" alt=\"\" class=\"wp-image-27477\" srcset=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2025\/01\/4-foto-Ana-Mendes-Prosa-de-Interesse-1024x683.jpg 1024w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2025\/01\/4-foto-Ana-Mendes-Prosa-de-Interesse-300x200.jpg 300w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2025\/01\/4-foto-Ana-Mendes-Prosa-de-Interesse-768x512.jpg 768w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2025\/01\/4-foto-Ana-Mendes-Prosa-de-Interesse-1536x1024.jpg 1536w, https:\/\/centrosabia.org.br\/wp-content\/uploads\/2025\/01\/4-foto-Ana-Mendes-Prosa-de-Interesse-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Ana Mendes | Colecci\u00f3n Centro Sabi\u00e1<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Las elecciones municipales son de gran importancia para la poblaci\u00f3n, porque en el municipio es donde ocurre todo. En el contexto pol\u00edtico actual, estas elecciones son fundamentales para la democracia brasile\u00f1a. Los 5.565 municipios de Brasil ya han elegido a los alcaldes y concejales que se encargar\u00e1n de elaborar las leyes y las pol\u00edticas p\u00fablicas que se aplicar\u00e1n en los pr\u00f3ximos a\u00f1os.  <\/p>\n\n<p class=\"wp-block-paragraph\">A los nuevos representantes municipales les esperan muchos retos en el pr\u00f3ximo mandato, entre ellos intensificar los compromisos existentes e iniciar nuevas acciones en defensa del medio ambiente y del clima, que deben ser prioritarias. Con la velocidad del cambio clim\u00e1tico, es esencial la acci\u00f3n permanente de las tres esferas de gobierno y de la poblaci\u00f3n, pues de lo contrario no se podr\u00e1n revertir los da\u00f1os ya causados. <\/p>\n\n<p class=\"wp-block-paragraph\">Otro reto importante es la Soberan\u00eda y Seguridad Alimentaria y Nutricional <strong>(<\/strong>SAN). Desde 2003, Brasil viene formulando pol\u00edticas en este \u00e1mbito, como la creaci\u00f3n del Sistema Nacional de Soberan\u00eda y Seguridad Alimentaria, que hasta 2015 anim\u00f3 a los estados y municipios a crear sus propias estrategias de SAN. Estas acciones se interrumpieron en los dos gobiernos federales anteriores, pero se reanudaron en 2023 debido a la urgencia de hacer frente a la Inseguridad Alimentaria y Nutricional <strong>(InSAN<\/strong> ), y en consecuencia al hambre, especialmente tras la pandemia del Covid-19.    <\/p>\n\n<p class=\"wp-block-paragraph\">No es un reto f\u00e1cil de afrontar; hay mucha resistencia por parte de los gestores municipales a unirse al sistema y asumir la responsabilidad de elaborar pol\u00edticas y planes locales para hacer frente al hambre. El estado de Pernambuco tiene 185 municipios y s\u00f3lo 25 se han adherido al Sistema Estatal de Seguridad Alimentaria, es decir, s\u00f3lo el 13% del total. <\/p>\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la Ley 11.346 de 2006, la Soberan\u00eda y Seguridad Alimentaria y Nutricional se define como la realizaci\u00f3n del derecho universal al acceso regular y permanente a alimentos de calidad en cantidad suficiente, sin comprometer el acceso a otras necesidades esenciales. Este concepto se basa en pr\u00e1cticas alimentarias que promuevan la salud, respeten la diversidad cultural y sean sostenibles desde el punto de vista medioambiental, econ\u00f3mico, social y cultural. <\/p>\n\n<p class=\"wp-block-paragraph\">La noci\u00f3n de SAN forma parte del derecho de todo ciudadano a estar seguro en relaci\u00f3n con la alimentaci\u00f3n y la nutrici\u00f3n en t\u00e9rminos de suficiencia (protecci\u00f3n contra el hambre y la malnutrici\u00f3n), calidad (prevenci\u00f3n de enfermedades relacionadas con la alimentaci\u00f3n) y adecuaci\u00f3n (adecuaci\u00f3n a las circunstancias sociales, medioambientales y culturales). Se considera que una alimentaci\u00f3n es adecuada cuando, adem\u00e1s de ser equilibrada desde el punto de vista nutricional, contribuye a la formaci\u00f3n de seres humanos sanos y conscientes de sus derechos y deberes y de su responsabilidad para con el medio ambiente y la calidad de vida de las personas a su cargo (SALLES-COSTA et al).  <\/p>\n\n<p class=\"wp-block-paragraph\">Esperar que estas acciones provengan s\u00f3lo del gobierno federal, sin la participaci\u00f3n efectiva de los municipios, es tener la certeza de que, adem\u00e1s de requerir mucho m\u00e1s tiempo para lograr resultados positivos, no se garantizar\u00e1 la cobertura universal. No hay otro camino que la amplia participaci\u00f3n de la sociedad civil a trav\u00e9s de sus organizaciones, su presencia en los consejos de pol\u00edticas p\u00fablicas y su contribuci\u00f3n permanente a trav\u00e9s del cabildeo sistem\u00e1tico en la formulaci\u00f3n y seguimiento de las pol\u00edticas de SAN. <\/p>\n\n<p class=\"has-palette-color-1-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\"><strong>Consulta:<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">BRASIL. \u00abLey n.\u00ba 11.346, de 15 de septiembre de 2006. Crea el Sistema Nacional de Seguridad Alimentaria y Nutricional &#8211; Sisan con vistas a garantizar el derecho humano a una alimentaci\u00f3n adecuada y dicta otras disposiciones\u00bb, Brasilia, 2006. <\/p>\n\n<p class=\"wp-block-paragraph\">SALLES-COSTA, Rosana et al. Sistemas alimentarios, hambre e inseguridad alimentaria en Brasil. R\u00edo de Janeiro: Fiocruz, 2022.  <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":27479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ano":0,"footnotes":""},"categories":[218],"tags":[],"class_list":["post-27482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-es"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El reto de las nuevas administraciones municipales con la soberan\u00eda y la seguridad alimentarias - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El reto de las nuevas administraciones municipales con la soberan\u00eda y la seguridad alimentarias - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-28T12:28:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-28T17:01:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2025\/01\/4-foto-Ana-Mendes-Prosa-de-Interesse-300x200.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Darliton\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Darliton\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2025\\\/01\\\/28\\\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2025\\\/01\\\/28\\\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\\\/\"},\"author\":{\"name\":\"Darliton\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/person\\\/7e83deaeb43644ce5b93a21b9d24c8d6\"},\"headline\":\"El reto de las nuevas administraciones municipales con la soberan\u00eda y la seguridad alimentarias\",\"datePublished\":\"2025-01-28T12:28:12+00:00\",\"dateModified\":\"2025-01-28T17:01:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2025\\\/01\\\/28\\\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\\\/\"},\"wordCount\":669,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2025\\\/01\\\/28\\\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/4-foto-Ana-Mendes-Prosa-de-Interesse.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2025\\\/01\\\/28\\\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2025\\\/01\\\/28\\\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\\\/\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2025\\\/01\\\/28\\\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\\\/\",\"name\":\"El reto de las nuevas administraciones municipales con la soberan\u00eda y la seguridad alimentarias - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2025\\\/01\\\/28\\\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2025\\\/01\\\/28\\\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/4-foto-Ana-Mendes-Prosa-de-Interesse.jpg\",\"datePublished\":\"2025-01-28T12:28:12+00:00\",\"dateModified\":\"2025-01-28T17:01:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2025\\\/01\\\/28\\\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2025\\\/01\\\/28\\\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2025\\\/01\\\/28\\\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/4-foto-Ana-Mendes-Prosa-de-Interesse.jpg\",\"contentUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/4-foto-Ana-Mendes-Prosa-de-Interesse.jpg\",\"width\":2500,\"height\":1667,\"caption\":\"O s\u00edtio Po\u00e7o Grande se localiza no munic\u00edpio de Flores, na regi\u00e3o do Sert\u00e3o do Paje\u00fa. Cerca de 30 fam\u00edlias vivem na localidade. Quase todas as fam\u00edlias tem cisternas que coletam as \u00e1guas das chuvas de diferentes maneiras. Outros modos de poupar \u00e1gua ou de ter acesso a ela entretanto, s\u00e3o necess\u00e1rios. A \u00e1gua das cisternas normalmente s\u00e3o utilizadas para beber e comer. J\u00e1 a \u00e1gua do rio Paje\u00fa, que nasce na cidade de Itapeti, \u00e9 puxada com bomba ou carregada com tambor, em carro\u00e7as de animais, entretanto, durante um certo per\u00edodo do ano uma parte do rio seca e n\u00e3o abastece toda a comunidade\\\/s\u00edtio. Uma barragem foi constru\u00edda, em 1982, deveria solucionar o problema. Alguns conflitos entre moradores, entretanto, est\u00e3o impedindo que a \u00e1gua chegue a todos com facilidade. Outro modo de aproveitamento da \u00e1gua \u00e9 a reutiliza\u00e7\u00e3o de \u00e1guas cinzas, implementada pela organiza\u00e7\u00e3o Sabi\u00e1, h\u00e1 cerca de dois anos. Em Po\u00e7o Grande seis fam\u00edlias est\u00e3o experimentando o sistema que serve para aguar principalmente as planta\u00e7\u00f5es de forragem, que serve de alimento para os animais. A barragem do Po\u00e7o Grande constru\u00edda em 1982 deveria ser a solu\u00e7\u00e3o para o abastecimento de todos, mas um conflito que acontece desde que ela foi constru\u00edda n\u00e3o permite que a \u00e1gua chegue com tanta facilidade a todos. Os moradores da parte de baixo do rio, reclamam que os moradores da parte de cima n\u00e3o querem que a barragem seja aberta nos per\u00edodos mais secos, tal como foi acertado entre a Associa\u00e7\u00e3o dos Trabalhadores Rurais do Po\u00e7o Grande, os moradores do munic\u00edpio de Carna\u00edba, a Ag\u00eancia Pernambucana de \u00c1guas e Clima (APAC) e representantes do munic\u00edpio de Carna\u00edba e do governo do estado de Pernambuco em dezembro de 2013.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/2025\\\/01\\\/28\\\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El reto de las nuevas administraciones municipales con la soberan\u00eda y la seguridad alimentarias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\",\"name\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\",\"name\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo.png\",\"width\":174,\"height\":84,\"caption\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/person\\\/7e83deaeb43644ce5b93a21b9d24c8d6\",\"name\":\"Darliton\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/abb43c9d012bc9e4677cba1d82588694a509da0a3479cb06ce66c26da27e1642?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/abb43c9d012bc9e4677cba1d82588694a509da0a3479cb06ce66c26da27e1642?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/abb43c9d012bc9e4677cba1d82588694a509da0a3479cb06ce66c26da27e1642?s=96&d=mm&r=g\",\"caption\":\"Darliton\"},\"description\":\"Comunicador popular, administrador, p\u00f3s-graduado em projetos sociais e pol\u00edticas p\u00fablicas, especialista media social, militante da agroecologia, conviv\u00eancia com semi\u00e1rido, direitos humanos, preserva\u00e7\u00e3o ambiental e direitos de trabalhadoras e trabalhadores.\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/author\\\/darliton\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El reto de las nuevas administraciones municipales con la soberan\u00eda y la seguridad alimentarias - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/","og_locale":"es_ES","og_type":"article","og_title":"El reto de las nuevas administraciones municipales con la soberan\u00eda y la seguridad alimentarias - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","og_url":"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/","og_site_name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","article_published_time":"2025-01-28T12:28:12+00:00","article_modified_time":"2025-01-28T17:01:11+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2025\/01\/4-foto-Ana-Mendes-Prosa-de-Interesse-300x200.jpg","type":"image\/jpeg"}],"author":"Darliton","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Darliton","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/#article","isPartOf":{"@id":"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/"},"author":{"name":"Darliton","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/person\/7e83deaeb43644ce5b93a21b9d24c8d6"},"headline":"El reto de las nuevas administraciones municipales con la soberan\u00eda y la seguridad alimentarias","datePublished":"2025-01-28T12:28:12+00:00","dateModified":"2025-01-28T17:01:11+00:00","mainEntityOfPage":{"@id":"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/"},"wordCount":669,"commentCount":0,"publisher":{"@id":"https:\/\/centrosabia.org.br\/es\/#organization"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/#primaryimage"},"thumbnailUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2025\/01\/4-foto-Ana-Mendes-Prosa-de-Interesse.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/","url":"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/","name":"El reto de las nuevas administraciones municipales con la soberan\u00eda y la seguridad alimentarias - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","isPartOf":{"@id":"https:\/\/centrosabia.org.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/#primaryimage"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/#primaryimage"},"thumbnailUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2025\/01\/4-foto-Ana-Mendes-Prosa-de-Interesse.jpg","datePublished":"2025-01-28T12:28:12+00:00","dateModified":"2025-01-28T17:01:11+00:00","breadcrumb":{"@id":"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/#primaryimage","url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2025\/01\/4-foto-Ana-Mendes-Prosa-de-Interesse.jpg","contentUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2025\/01\/4-foto-Ana-Mendes-Prosa-de-Interesse.jpg","width":2500,"height":1667,"caption":"O s\u00edtio Po\u00e7o Grande se localiza no munic\u00edpio de Flores, na regi\u00e3o do Sert\u00e3o do Paje\u00fa. Cerca de 30 fam\u00edlias vivem na localidade. Quase todas as fam\u00edlias tem cisternas que coletam as \u00e1guas das chuvas de diferentes maneiras. Outros modos de poupar \u00e1gua ou de ter acesso a ela entretanto, s\u00e3o necess\u00e1rios. A \u00e1gua das cisternas normalmente s\u00e3o utilizadas para beber e comer. J\u00e1 a \u00e1gua do rio Paje\u00fa, que nasce na cidade de Itapeti, \u00e9 puxada com bomba ou carregada com tambor, em carro\u00e7as de animais, entretanto, durante um certo per\u00edodo do ano uma parte do rio seca e n\u00e3o abastece toda a comunidade\/s\u00edtio. Uma barragem foi constru\u00edda, em 1982, deveria solucionar o problema. Alguns conflitos entre moradores, entretanto, est\u00e3o impedindo que a \u00e1gua chegue a todos com facilidade. Outro modo de aproveitamento da \u00e1gua \u00e9 a reutiliza\u00e7\u00e3o de \u00e1guas cinzas, implementada pela organiza\u00e7\u00e3o Sabi\u00e1, h\u00e1 cerca de dois anos. Em Po\u00e7o Grande seis fam\u00edlias est\u00e3o experimentando o sistema que serve para aguar principalmente as planta\u00e7\u00f5es de forragem, que serve de alimento para os animais. A barragem do Po\u00e7o Grande constru\u00edda em 1982 deveria ser a solu\u00e7\u00e3o para o abastecimento de todos, mas um conflito que acontece desde que ela foi constru\u00edda n\u00e3o permite que a \u00e1gua chegue com tanta facilidade a todos. Os moradores da parte de baixo do rio, reclamam que os moradores da parte de cima n\u00e3o querem que a barragem seja aberta nos per\u00edodos mais secos, tal como foi acertado entre a Associa\u00e7\u00e3o dos Trabalhadores Rurais do Po\u00e7o Grande, os moradores do munic\u00edpio de Carna\u00edba, a Ag\u00eancia Pernambucana de \u00c1guas e Clima (APAC) e representantes do munic\u00edpio de Carna\u00edba e do governo do estado de Pernambuco em dezembro de 2013."},{"@type":"BreadcrumbList","@id":"https:\/\/centrosabia.org.br\/es\/2025\/01\/28\/o-desafio-das-novas-gestoes-municipais-com-a-soberania-e-a-seguranca-alimentar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/centrosabia.org.br\/es\/"},{"@type":"ListItem","position":2,"name":"El reto de las nuevas administraciones municipales con la soberan\u00eda y la seguridad alimentarias"}]},{"@type":"WebSite","@id":"https:\/\/centrosabia.org.br\/es\/#website","url":"https:\/\/centrosabia.org.br\/es\/","name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","description":"","publisher":{"@id":"https:\/\/centrosabia.org.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrosabia.org.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrosabia.org.br\/es\/#organization","name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","url":"https:\/\/centrosabia.org.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2021\/10\/logo.png","contentUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2021\/10\/logo.png","width":174,"height":84,"caption":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/person\/7e83deaeb43644ce5b93a21b9d24c8d6","name":"Darliton","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/abb43c9d012bc9e4677cba1d82588694a509da0a3479cb06ce66c26da27e1642?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/abb43c9d012bc9e4677cba1d82588694a509da0a3479cb06ce66c26da27e1642?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/abb43c9d012bc9e4677cba1d82588694a509da0a3479cb06ce66c26da27e1642?s=96&d=mm&r=g","caption":"Darliton"},"description":"Comunicador popular, administrador, p\u00f3s-graduado em projetos sociais e pol\u00edticas p\u00fablicas, especialista media social, militante da agroecologia, conviv\u00eancia com semi\u00e1rido, direitos humanos, preserva\u00e7\u00e3o ambiental e direitos de trabalhadoras e trabalhadores.","url":"https:\/\/centrosabia.org.br\/es\/author\/darliton\/"}]}},"_links":{"self":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts\/27482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/comments?post=27482"}],"version-history":[{"count":2,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts\/27482\/revisions"}],"predecessor-version":[{"id":27486,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts\/27482\/revisions\/27486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/media\/27479"}],"wp:attachment":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/media?parent=27482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/categories?post=27482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/tags?post=27482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}