{"id":1224,"count":1,"description":"","link":"https:\/\/centrosabia.org.br\/es\/tag\/intercambio-de-saberes-es\/","name":"Interc\u00e2mbio de Saberes","slug":"intercambio-de-saberes-es","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivos Interc\u00e2mbio de Saberes - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrosabia.org.br\/es\/tag\/intercambio-de-saberes-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Interc\u00e2mbio de Saberes - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrosabia.org.br\/es\/tag\/intercambio-de-saberes-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/tag\\\/intercambio-de-saberes-es\\\/\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/tag\\\/intercambio-de-saberes-es\\\/\",\"name\":\"Arquivos Interc\u00e2mbio de Saberes - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/tag\\\/intercambio-de-saberes-es\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/tag\\\/intercambio-de-saberes-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interc\u00e2mbio de Saberes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\",\"name\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#organization\",\"name\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/centrosabia.org.br\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo.png\",\"width\":174,\"height\":84,\"caption\":\"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1\"},\"image\":{\"@id\":\"https:\\\/\\\/centrosabia.org.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Interc\u00e2mbio de Saberes - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrosabia.org.br\/es\/tag\/intercambio-de-saberes-es\/","og_locale":"es_ES","og_type":"article","og_title":"Arquivos Interc\u00e2mbio de Saberes - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","og_url":"https:\/\/centrosabia.org.br\/es\/tag\/intercambio-de-saberes-es\/","og_site_name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/centrosabia.org.br\/es\/tag\/intercambio-de-saberes-es\/","url":"https:\/\/centrosabia.org.br\/es\/tag\/intercambio-de-saberes-es\/","name":"Arquivos Interc\u00e2mbio de Saberes - Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","isPartOf":{"@id":"https:\/\/centrosabia.org.br\/es\/#website"},"breadcrumb":{"@id":"https:\/\/centrosabia.org.br\/es\/tag\/intercambio-de-saberes-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/centrosabia.org.br\/es\/tag\/intercambio-de-saberes-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/centrosabia.org.br\/es\/"},{"@type":"ListItem","position":2,"name":"Interc\u00e2mbio de Saberes"}]},{"@type":"WebSite","@id":"https:\/\/centrosabia.org.br\/es\/#website","url":"https:\/\/centrosabia.org.br\/es\/","name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","description":"","publisher":{"@id":"https:\/\/centrosabia.org.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrosabia.org.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrosabia.org.br\/es\/#organization","name":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1","url":"https:\/\/centrosabia.org.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2021\/10\/logo.png","contentUrl":"https:\/\/centrosabia.org.br\/wp-content\/uploads\/2021\/10\/logo.png","width":174,"height":84,"caption":"Centro de Desenvolvimento Agroecol\u00f3gico Sabi\u00e1"},"image":{"@id":"https:\/\/centrosabia.org.br\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/tags\/1224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/centrosabia.org.br\/es\/wp-json\/wp\/v2\/posts?tags=1224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}